<?php?>{"id":18,"date":"2016-05-31T14:31:37","date_gmt":"2016-05-31T14:31:37","guid":{"rendered":"http:\/\/192.168.2.2\/liceogrc\/?page_id=18"},"modified":"2016-12-19T14:22:46","modified_gmt":"2016-12-19T14:22:46","slug":"mision-y-vision","status":"publish","type":"page","link":"https:\/\/www.liceogrc.cl\/index.php\/mision-y-vision\/","title":{"rendered":"Misi\u00f3n Institucional"},"content":{"rendered":"<p style=\"text-align: justify;\">El Liceo Galvarino Riveros C\u00e1rdenas, en su calidad de establecimiento educacional Humanista &#8211; Cient\u00edfico, tiene como misi\u00f3n el desarrollo integral de los alumnos que forma, a trav\u00e9s de un proceso educativo, con el que se pretende lograr aprendizajes significativos y permanentes, con metodolog\u00edas innovadoras, motivadoras, creativas, inclusivas y contextualizadas en nuestro entorno socio-cultural. Esto, en un ambiente respetuoso, solidario, integrador y democr\u00e1tico que involucra, en su quehacer educativo, a todos los integrantes de la comunidad: profesores, asistentes de la educaci\u00f3n, estudiantes, padres y apoderados; cada uno en su respectivo rol y responsabilidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Liceo Galvarino Riveros C\u00e1rdenas, en su calidad de establecimiento educacional Humanista &#8211; Cient\u00edfico, tiene como misi\u00f3n el desarrollo integral de los alumnos que forma, a trav\u00e9s de un proceso educativo, con el que se pretende lograr aprendizajes significativos y permanentes, con metodolog\u00edas innovadoras, motivadoras, creativas, inclusivas y contextualizadas en nuestro entorno socio-cultural. Esto, en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-18","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.liceogrc.cl\/index.php\/wp-json\/wp\/v2\/pages\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.liceogrc.cl\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.liceogrc.cl\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.liceogrc.cl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.liceogrc.cl\/index.php\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":7,"href":"https:\/\/www.liceogrc.cl\/index.php\/wp-json\/wp\/v2\/pages\/18\/revisions"}],"predecessor-version":[{"id":2348,"href":"https:\/\/www.liceogrc.cl\/index.php\/wp-json\/wp\/v2\/pages\/18\/revisions\/2348"}],"wp:attachment":[{"href":"https:\/\/www.liceogrc.cl\/index.php\/wp-json\/wp\/v2\/media?parent=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}